{"id":1052,"date":"2024-04-06T21:05:24","date_gmt":"2024-04-06T19:05:24","guid":{"rendered":"http:\/\/10.100.30.111\/?post_type=nota_prensa&#038;p=1052"},"modified":"2025-10-30T11:12:46","modified_gmt":"2025-10-30T15:12:46","slug":"el-ministerio-de-la-presidencia-y-la-agetic-conmemoran-el-8m-con-una-nuevageneracion-de-ninas-y-adolescentes-en-la-ciencia-y-la-tecnologia","status":"publish","type":"nota_prensa","link":"https:\/\/seprec.gob.bo\/index.php\/nota_prensa\/el-ministerio-de-la-presidencia-y-la-agetic-conmemoran-el-8m-con-una-nuevageneracion-de-ninas-y-adolescentes-en-la-ciencia-y-la-tecnologia\/","title":{"rendered":"SEPREC ENCIENDE LA CHISPA DEL EMPRENDIMIENTO EN SANTA CRUZ"},"featured_media":0,"template":"","class_list":["post-1052","nota_prensa","type-nota_prensa","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/seprec.gob.bo\/index.php\/wp-json\/wp\/v2\/nota_prensa\/1052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seprec.gob.bo\/index.php\/wp-json\/wp\/v2\/nota_prensa"}],"about":[{"href":"https:\/\/seprec.gob.bo\/index.php\/wp-json\/wp\/v2\/types\/nota_prensa"}],"wp:attachment":[{"href":"https:\/\/seprec.gob.bo\/index.php\/wp-json\/wp\/v2\/media?parent=1052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}